{"id":16377,"date":"2024-08-03T13:09:22","date_gmt":"2024-08-03T13:09:22","guid":{"rendered":"https:\/\/ontheflipsidecomics.com\/?page_id=16377"},"modified":"2026-02-11T17:02:43","modified_gmt":"2026-02-11T22:02:43","slug":"konga-new-comic","status":"publish","type":"page","link":"https:\/\/ontheflipsidecomics.com\/it\/konga-new-comic\/","title":{"rendered":"Konga Main"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16377\" class=\"elementor elementor-16377\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e496e3b elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"1e496e3b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72462baa\" data-id=\"72462baa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67d77621 elementor-widget elementor-widget-image\" data-id=\"67d77621\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/elementor\/thumbs\/KONG0201-rg5keghz25hiimky34y99151yi8b48yb6rne7z4y4g.jpg\" title=\"KONG0201\" alt=\"KONG0201\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cf201f2 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"3cf201f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c3166d4\" data-id=\"6c3166d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e52605d elementor-widget elementor-widget-image\" data-id=\"4e52605d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"1517\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0202.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27308\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0202.jpg 984w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0202-195x300.jpg 195w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0202-664x1024.jpg 664w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0202-768x1184.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0202-300x463.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0202-600x925.jpg 600w\" sizes=\"auto, (max-width: 984px) 100vw, 984px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-662ca698 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"662ca698\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-47dcbdbf\" data-id=\"47dcbdbf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42fcb915 elementor-widget elementor-widget-image\" data-id=\"42fcb915\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"980\" height=\"1404\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0203.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27309\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0203.jpg 980w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0203-209x300.jpg 209w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0203-715x1024.jpg 715w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0203-768x1100.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0203-300x430.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0203-600x860.jpg 600w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bcdeb74 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"6bcdeb74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f08e01c\" data-id=\"2f08e01c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a3760b3 elementor-widget elementor-widget-image\" data-id=\"4a3760b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"992\" height=\"1413\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0204.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27310\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0204.jpg 992w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0204-211x300.jpg 211w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0204-719x1024.jpg 719w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0204-768x1094.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0204-300x427.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0204-600x855.jpg 600w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17ea4834 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"17ea4834\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b7d5a17\" data-id=\"3b7d5a17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41e32ac5 elementor-widget elementor-widget-image\" data-id=\"41e32ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"988\" height=\"1409\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0205.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27311\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0205.jpg 988w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0205-210x300.jpg 210w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0205-718x1024.jpg 718w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0205-768x1095.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0205-300x428.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0205-600x856.jpg 600w\" sizes=\"auto, (max-width: 988px) 100vw, 988px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1dacb6ff elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"1dacb6ff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61e0186b\" data-id=\"61e0186b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c82e418 elementor-widget elementor-widget-image\" data-id=\"3c82e418\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"941\" height=\"1429\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0206.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27312\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0206.jpg 941w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0206-198x300.jpg 198w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0206-674x1024.jpg 674w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0206-768x1166.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0206-300x456.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0206-600x911.jpg 600w\" sizes=\"auto, (max-width: 941px) 100vw, 941px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73db6f96 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"73db6f96\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5bf2e93\" data-id=\"5bf2e93\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38a98cf4 elementor-widget elementor-widget-image\" data-id=\"38a98cf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"996\" height=\"1409\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0207.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27313\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0207.jpg 996w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0207-212x300.jpg 212w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0207-724x1024.jpg 724w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0207-768x1086.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0207-300x424.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0207-600x849.jpg 600w\" sizes=\"auto, (max-width: 996px) 100vw, 996px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bf4ac02 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"bf4ac02\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-106690c8\" data-id=\"106690c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cf509d5 elementor-widget elementor-widget-image\" data-id=\"7cf509d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"988\" height=\"1421\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0208.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27314\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0208.jpg 988w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0208-209x300.jpg 209w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0208-712x1024.jpg 712w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0208-768x1105.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0208-300x431.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0208-600x863.jpg 600w\" sizes=\"auto, (max-width: 988px) 100vw, 988px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-465c6145 elementor-widget elementor-widget-image\" data-id=\"465c6145\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1014\" height=\"1416\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0209.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27315\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0209.jpg 1014w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0209-215x300.jpg 215w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0209-733x1024.jpg 733w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0209-768x1072.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0209-300x419.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0209-600x838.jpg 600w\" sizes=\"auto, (max-width: 1014px) 100vw, 1014px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-129714e7 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"129714e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6690717\" data-id=\"6690717\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37a6c44a elementor-widget elementor-widget-image\" data-id=\"37a6c44a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"996\" height=\"1417\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0210.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27316\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0210.jpg 996w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0210-211x300.jpg 211w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0210-720x1024.jpg 720w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0210-768x1093.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0210-300x427.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0210-600x854.jpg 600w\" sizes=\"auto, (max-width: 996px) 100vw, 996px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67c64b53 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"67c64b53\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-78f33e6c\" data-id=\"78f33e6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2293aa6a elementor-widget elementor-widget-image\" data-id=\"2293aa6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1002\" height=\"1410\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0211.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27317\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0211.jpg 1002w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0211-213x300.jpg 213w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0211-728x1024.jpg 728w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0211-768x1081.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0211-300x422.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0211-600x844.jpg 600w\" sizes=\"auto, (max-width: 1002px) 100vw, 1002px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7934b7ba elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7934b7ba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-223e4381\" data-id=\"223e4381\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16f58b6d elementor-widget elementor-widget-image\" data-id=\"16f58b6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/atomiccomicsemporium.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/elementor\/thumbs\/Atomic_ad1-qp7nqv7v6zq7pai9s0pphrqubawarha3bpght8zwn4.jpg\" title=\"Atomic_ad1\" alt=\"Atomic_ad1\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bb21750 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5bb21750\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32af17f9\" data-id=\"32af17f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-195de866 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"195de866\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1002\" height=\"1404\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0212.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27318\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0212.jpg 1002w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0212-214x300.jpg 214w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0212-731x1024.jpg 731w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0212-768x1076.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0212-300x420.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0212-600x841.jpg 600w\" sizes=\"auto, (max-width: 1002px) 100vw, 1002px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1975b8d2 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"1975b8d2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40826e4f\" data-id=\"40826e4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23155d65 elementor-widget elementor-widget-image\" data-id=\"23155d65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1004\" height=\"1417\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0213.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27319\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0213.jpg 1004w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0213-213x300.jpg 213w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0213-726x1024.jpg 726w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0213-768x1084.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0213-300x423.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0213-600x847.jpg 600w\" sizes=\"auto, (max-width: 1004px) 100vw, 1004px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-425f8efb elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"425f8efb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-167236e1\" data-id=\"167236e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4baa29d2 elementor-widget elementor-widget-image\" data-id=\"4baa29d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"996\" height=\"1413\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0214.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27320\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0214.jpg 996w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0214-211x300.jpg 211w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0214-722x1024.jpg 722w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0214-768x1090.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0214-300x426.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0214-600x851.jpg 600w\" sizes=\"auto, (max-width: 996px) 100vw, 996px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30164aa6 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"30164aa6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-458d02a0\" data-id=\"458d02a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38e6672e elementor-widget elementor-widget-image\" data-id=\"38e6672e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"975\" height=\"1417\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0215.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27321\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0215.jpg 975w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0215-206x300.jpg 206w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0215-705x1024.jpg 705w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0215-768x1116.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0215-300x436.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0215-600x872.jpg 600w\" sizes=\"auto, (max-width: 975px) 100vw, 975px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7125d7ed elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7125d7ed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-51c0db7c\" data-id=\"51c0db7c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a790fb3 elementor-widget elementor-widget-image\" data-id=\"2a790fb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"996\" height=\"1409\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0216.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27322\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0216.jpg 996w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0216-212x300.jpg 212w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0216-724x1024.jpg 724w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0216-768x1086.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0216-300x424.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0216-600x849.jpg 600w\" sizes=\"auto, (max-width: 996px) 100vw, 996px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39f92823 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"39f92823\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ea22f76\" data-id=\"5ea22f76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fd27570 elementor-widget elementor-widget-image\" data-id=\"1fd27570\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"1400\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0217.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27323\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0217.jpg 984w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0217-211x300.jpg 211w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0217-720x1024.jpg 720w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0217-768x1093.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0217-300x427.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0217-600x854.jpg 600w\" sizes=\"auto, (max-width: 984px) 100vw, 984px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d33a040 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"6d33a040\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a6986e2\" data-id=\"a6986e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44f0697c elementor-widget elementor-widget-image\" data-id=\"44f0697c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"996\" height=\"1392\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0218.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27324\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0218.jpg 996w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0218-215x300.jpg 215w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0218-733x1024.jpg 733w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0218-768x1073.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0218-300x419.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0218-600x839.jpg 600w\" sizes=\"auto, (max-width: 996px) 100vw, 996px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38132b1a elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"38132b1a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-76e7fe48\" data-id=\"76e7fe48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4649e1d1 elementor-widget elementor-widget-image\" data-id=\"4649e1d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"988\" height=\"1400\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0219.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27325\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0219.jpg 988w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0219-212x300.jpg 212w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0219-723x1024.jpg 723w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0219-768x1088.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0219-300x425.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0219-600x850.jpg 600w\" sizes=\"auto, (max-width: 988px) 100vw, 988px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-498f5dc4 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"498f5dc4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d2fbe57\" data-id=\"5d2fbe57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d719f6f elementor-widget elementor-widget-image\" data-id=\"1d719f6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1405\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0220.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27326\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0220.jpg 1000w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0220-214x300.jpg 214w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0220-729x1024.jpg 729w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0220-768x1079.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0220-300x422.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0220-600x843.jpg 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2281fd4b elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"2281fd4b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-166d7b88\" data-id=\"166d7b88\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-477c9d77 elementor-widget elementor-widget-image\" data-id=\"477c9d77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1008\" height=\"1417\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0221.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27327\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0221.jpg 1008w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0221-213x300.jpg 213w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0221-728x1024.jpg 728w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0221-768x1080.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0221-300x422.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0221-600x843.jpg 600w\" sizes=\"auto, (max-width: 1008px) 100vw, 1008px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25b58a2b elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"25b58a2b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19793a4\" data-id=\"19793a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d37d37b elementor-widget elementor-widget-image\" data-id=\"6d37d37b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"992\" height=\"1438\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0222.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27328\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0222.jpg 992w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0222-207x300.jpg 207w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0222-706x1024.jpg 706w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0222-768x1113.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0222-300x435.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0222-600x870.jpg 600w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ffe61bd elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"3ffe61bd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-67a72b0\" data-id=\"67a72b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3867979e elementor-widget elementor-widget-image\" data-id=\"3867979e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"996\" height=\"1396\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0223.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27329\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0223.jpg 996w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0223-214x300.jpg 214w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0223-731x1024.jpg 731w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0223-768x1076.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0223-300x420.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0223-600x841.jpg 600w\" sizes=\"auto, (max-width: 996px) 100vw, 996px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-221e54cf elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"221e54cf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30a3649\" data-id=\"30a3649\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17fa4268 elementor-widget elementor-widget-image\" data-id=\"17fa4268\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1012\" height=\"1431\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0224.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27330\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0224.jpg 1012w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0224-212x300.jpg 212w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0224-724x1024.jpg 724w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0224-768x1086.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0224-300x424.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0224-600x848.jpg 600w\" sizes=\"auto, (max-width: 1012px) 100vw, 1012px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18bec8b8 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"18bec8b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2eb70597\" data-id=\"2eb70597\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-728eddb6 elementor-widget elementor-widget-image\" data-id=\"728eddb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"988\" height=\"1396\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0225.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27331\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0225.jpg 988w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0225-212x300.jpg 212w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0225-725x1024.jpg 725w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0225-768x1085.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0225-300x424.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0225-600x848.jpg 600w\" sizes=\"auto, (max-width: 988px) 100vw, 988px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79b86fe4 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"79b86fe4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5aa1e4de\" data-id=\"5aa1e4de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b443d32 elementor-widget elementor-widget-image\" data-id=\"1b443d32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"1413\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0226.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27332\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0226.jpg 984w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0226-209x300.jpg 209w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0226-713x1024.jpg 713w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0226-768x1103.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0226-300x431.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0226-600x862.jpg 600w\" sizes=\"auto, (max-width: 984px) 100vw, 984px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a13fac9 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"6a13fac9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4aa863a9\" data-id=\"4aa863a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a561ecd elementor-widget elementor-widget-image\" data-id=\"2a561ecd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1421\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0227.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27333\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0227.jpg 1000w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0227-211x300.jpg 211w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0227-721x1024.jpg 721w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0227-768x1091.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0227-300x426.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0227-600x853.jpg 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4cded385 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"4cded385\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-290c510\" data-id=\"290c510\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c2dcf71 elementor-widget elementor-widget-image\" data-id=\"1c2dcf71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"892\" height=\"1355\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0228.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27334\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0228.jpg 892w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0228-197x300.jpg 197w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0228-674x1024.jpg 674w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0228-768x1167.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0228-300x456.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0228-600x911.jpg 600w\" sizes=\"auto, (max-width: 892px) 100vw, 892px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a3cbd2d elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"1a3cbd2d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a35c0b2\" data-id=\"2a35c0b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-179541bf elementor-widget elementor-widget-image\" data-id=\"179541bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"925\" height=\"1379\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0229.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27335\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0229.jpg 925w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0229-201x300.jpg 201w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0229-687x1024.jpg 687w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0229-768x1145.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0229-300x447.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0229-600x894.jpg 600w\" sizes=\"auto, (max-width: 925px) 100vw, 925px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-277a4fa3 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"277a4fa3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b9343af\" data-id=\"b9343af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c7251da elementor-widget elementor-widget-image\" data-id=\"7c7251da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"996\" height=\"1409\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0230.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-27336\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0230.jpg 996w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0230-212x300.jpg 212w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0230-724x1024.jpg 724w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0230-768x1086.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0230-300x424.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0230-600x849.jpg 600w\" sizes=\"auto, (max-width: 996px) 100vw, 996px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-16b25f6 e-flex e-con-boxed e-con e-parent\" data-id=\"16b25f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-660bc6c elementor-widget elementor-widget-image\" data-id=\"660bc6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"728\" height=\"1024\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0231-728x1024.jpg\" class=\"attachment-large size-large wp-image-27337\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0231-728x1024.jpg 728w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0231-213x300.jpg 213w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0231-768x1080.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0231-300x422.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0231-600x844.jpg 600w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0231.jpg 984w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6691050 e-flex e-con-boxed e-con e-parent\" data-id=\"6691050\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1bef06c elementor-widget elementor-widget-image\" data-id=\"1bef06c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"1024\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0232-730x1024.jpg\" class=\"attachment-large size-large wp-image-27338\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0232-730x1024.jpg 730w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0232-214x300.jpg 214w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0232-768x1078.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0232-300x421.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0232-600x842.jpg 600w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0232.jpg 992w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e01bee7 e-flex e-con-boxed e-con e-parent\" data-id=\"e01bee7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a0bfce elementor-widget elementor-widget-image\" data-id=\"8a0bfce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"718\" height=\"1024\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0233-718x1024.jpg\" class=\"attachment-large size-large wp-image-27339\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0233-718x1024.jpg 718w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0233-210x300.jpg 210w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0233-768x1096.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0233-300x428.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0233-600x856.jpg 600w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0233.jpg 984w\" sizes=\"auto, (max-width: 718px) 100vw, 718px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-abfb5d9 e-flex e-con-boxed e-con e-parent\" data-id=\"abfb5d9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2516cb5 elementor-widget elementor-widget-image\" data-id=\"2516cb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"715\" height=\"1024\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0234-715x1024.jpg\" class=\"attachment-large size-large wp-image-27340\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0234-715x1024.jpg 715w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0234-209x300.jpg 209w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0234-768x1100.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0234-300x430.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0234-600x859.jpg 600w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0234.jpg 992w\" sizes=\"auto, (max-width: 715px) 100vw, 715px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-242c11a e-flex e-con-boxed e-con e-parent\" data-id=\"242c11a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a1958da elementor-widget elementor-widget-image\" data-id=\"a1958da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"1024\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0235-721x1024.jpg\" class=\"attachment-large size-large wp-image-27341\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0235-721x1024.jpg 721w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0235-211x300.jpg 211w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0235-768x1091.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0235-300x426.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0235-600x852.jpg 600w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0235.jpg 980w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e17ee2c e-flex e-con-boxed e-con e-parent\" data-id=\"e17ee2c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69b5caf elementor-widget elementor-widget-image\" data-id=\"69b5caf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"692\" height=\"1024\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0236-692x1024.jpg\" class=\"attachment-large size-large wp-image-27342\" alt=\"\" srcset=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0236-692x1024.jpg 692w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0236-203x300.jpg 203w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0236-768x1136.jpg 768w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0236-300x444.jpg 300w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0236-600x888.jpg 600w, https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2025\/12\/KONG0236.jpg 980w\" sizes=\"auto, (max-width: 692px) 100vw, 692px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_theme","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-16377","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Konga Main<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ontheflipsidecomics.com\/it\/konga-new-comic\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"ar\" \/>\n<meta property=\"og:locale:alternate\" content=\"de_DE\" \/>\n<meta property=\"og:locale:alternate\" content=\"es_MX\" \/>\n<meta property=\"og:locale:alternate\" content=\"fr_FR\" \/>\n<meta property=\"og:locale:alternate\" content=\"ja\" \/>\n<meta property=\"og:locale:alternate\" content=\"ko_KR\" \/>\n<meta property=\"og:locale:alternate\" content=\"nl_NL\" \/>\n<meta property=\"og:locale:alternate\" content=\"pt_BR\" \/>\n<meta property=\"og:locale:alternate\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Konga Main\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ontheflipsidecomics.com\/it\/konga-new-comic\/\" \/>\n<meta property=\"og:site_name\" content=\"Flipside Comics\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089482013557\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T22:02:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/elementor\/thumbs\/KONG0201-rg5keghz25hiimky34y99151yi8b48yb6rne7z4xoc.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@FlipsideComix\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/en\\\/konga-new-comic\\\/\",\"url\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/en\\\/konga-new-comic\\\/\",\"name\":\"Konga Main\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/en\\\/konga-new-comic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/en\\\/konga-new-comic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/KONG0201-rg5keghz25hiimky34y99151yi8b48yb6rne7z4xoc.jpg\",\"datePublished\":\"2024-08-03T13:09:22+00:00\",\"dateModified\":\"2026-02-11T22:02:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/en\\\/konga-new-comic\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ontheflipsidecomics.com\\\/en\\\/konga-new-comic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/en\\\/konga-new-comic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/KONG0201-rg5keghz25hiimky34y99151yi8b48yb6rne7z4xoc.jpg\",\"contentUrl\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/KONG0201-rg5keghz25hiimky34y99151yi8b48yb6rne7z4xoc.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/en\\\/konga-new-comic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Konga Main\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/\",\"name\":\"OntheFlipsideComics\",\"description\":\"Where Past and Present Collide to Make the Future\",\"publisher\":{\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/#organization\",\"name\":\"Flipside Comics\",\"alternateName\":\"Flipside Comix\",\"url\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LBC_logo-2.png\",\"contentUrl\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LBC_logo-2.png\",\"width\":295,\"height\":199,\"caption\":\"Flipside Comics\"},\"image\":{\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089482013557\",\"https:\\\/\\\/x.com\\\/FlipsideComix\",\"https:\\\/\\\/bsky.app\\\/profile\\\/flipsidecomics.bsky.social\",\"https:\\\/\\\/www.instagram.com\\\/flipsidecomix\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Konga Main","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ontheflipsidecomics.com\/it\/konga-new-comic\/","og_locale":"it_IT","og_type":"article","og_title":"[:en]Konga Main[:] - Where Past and Present Collide to Make the Future","og_url":"https:\/\/ontheflipsidecomics.com\/it\/konga-new-comic\/","og_site_name":"Flipside Comics","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100089482013557","article_modified_time":"2026-02-11T22:02:43+00:00","og_image":[{"url":"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/elementor\/thumbs\/KONG0201-rg5keghz25hiimky34y99151yi8b48yb6rne7z4xoc.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@FlipsideComix","twitter_misc":{"Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ontheflipsidecomics.com\/en\/konga-new-comic\/","url":"https:\/\/ontheflipsidecomics.com\/en\/konga-new-comic\/","name":"Konga Main","isPartOf":{"@id":"https:\/\/ontheflipsidecomics.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ontheflipsidecomics.com\/en\/konga-new-comic\/#primaryimage"},"image":{"@id":"https:\/\/ontheflipsidecomics.com\/en\/konga-new-comic\/#primaryimage"},"thumbnailUrl":"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/elementor\/thumbs\/KONG0201-rg5keghz25hiimky34y99151yi8b48yb6rne7z4xoc.jpg","datePublished":"2024-08-03T13:09:22+00:00","dateModified":"2026-02-11T22:02:43+00:00","breadcrumb":{"@id":"https:\/\/ontheflipsidecomics.com\/en\/konga-new-comic\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ontheflipsidecomics.com\/en\/konga-new-comic\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ontheflipsidecomics.com\/en\/konga-new-comic\/#primaryimage","url":"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/elementor\/thumbs\/KONG0201-rg5keghz25hiimky34y99151yi8b48yb6rne7z4xoc.jpg","contentUrl":"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/elementor\/thumbs\/KONG0201-rg5keghz25hiimky34y99151yi8b48yb6rne7z4xoc.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/ontheflipsidecomics.com\/en\/konga-new-comic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ontheflipsidecomics.com\/it\/"},{"@type":"ListItem","position":2,"name":"Konga Main"}]},{"@type":"WebSite","@id":"https:\/\/ontheflipsidecomics.com\/it\/#website","url":"https:\/\/ontheflipsidecomics.com\/it\/","name":"OntheFlipsideComics","description":"Where Past and Present Collide to Make the Future","publisher":{"@id":"https:\/\/ontheflipsidecomics.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ontheflipsidecomics.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ontheflipsidecomics.com\/it\/#organization","name":"Flipside Comics","alternateName":"Flipside Comix","url":"https:\/\/ontheflipsidecomics.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ontheflipsidecomics.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2022\/08\/LBC_logo-2.png","contentUrl":"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2022\/08\/LBC_logo-2.png","width":295,"height":199,"caption":"Flipside Comics"},"image":{"@id":"https:\/\/ontheflipsidecomics.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100089482013557","https:\/\/x.com\/FlipsideComix","https:\/\/bsky.app\/profile\/flipsidecomics.bsky.social","https:\/\/www.instagram.com\/flipsidecomix\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ontheflipsidecomics.com\/it\/wp-json\/wp\/v2\/pages\/16377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ontheflipsidecomics.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ontheflipsidecomics.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ontheflipsidecomics.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ontheflipsidecomics.com\/it\/wp-json\/wp\/v2\/comments?post=16377"}],"version-history":[{"count":566,"href":"https:\/\/ontheflipsidecomics.com\/it\/wp-json\/wp\/v2\/pages\/16377\/revisions"}],"predecessor-version":[{"id":27866,"href":"https:\/\/ontheflipsidecomics.com\/it\/wp-json\/wp\/v2\/pages\/16377\/revisions\/27866"}],"wp:attachment":[{"href":"https:\/\/ontheflipsidecomics.com\/it\/wp-json\/wp\/v2\/media?parent=16377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}