{"id":6450,"date":"2024-02-17T19:21:01","date_gmt":"2024-02-17T19:21:01","guid":{"rendered":"https:\/\/ontheflipsidecomics.com\/?page_id=6450"},"modified":"2024-02-21T11:58:41","modified_gmt":"2024-02-21T11:58:41","slug":"comics-index","status":"publish","type":"page","link":"https:\/\/ontheflipsidecomics.com\/nl\/comics-index\/","title":{"rendered":"Comics Index"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6450\" class=\"elementor elementor-6450\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-190758d elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"190758d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6060c50\" data-id=\"6060c50\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4730c9e elementor-widget elementor-widget-page-title\" data-id=\"4730c9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;align&quot;:&quot;center&quot;}\" data-widget_type=\"page-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n\t\t<div class=\"hfe-page-title hfe-page-title-wrapper elementor-widget-heading\">\n\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ontheflipsidecomics.com\/nl\">\n\t\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\n\t\t\t\t\t\t\t\t\n\t\t\t\tComics Index  \n\t\t\t<\/h2 > \n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b13b47c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b13b47c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-af5772d\" data-id=\"af5772d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09a1fcf elementor-widget elementor-widget-heading\" data-id=\"09a1fcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pick A Category &amp; START READIN'<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62f441d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62f441d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-569f2ff\" data-id=\"569f2ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-440dcbb stax-condition-yes stax-user_role_enabled-yes elementor-widget elementor-widget-text-editor\" data-id=\"440dcbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><strong><a href=\"#\">Kids<\/a>\u00a0 \u00a0<a href=\"#\"> Action \/ Adventure<\/a><span class=\"Apple-converted-space\">\u00a0 \u00a0 <a href=\"#\">\u00a0<\/a><\/span><a href=\"#\">Romance<\/a>\u00a0 \u00a0 <a href=\"#\">Humor<\/a>\u00a0 \u00a0 <a href=\"#\">Flipside Originals\u00a0<\/a> \u00a0 <a href=\"#\">Fantasy<\/a>\u00a0 \u00a0 <a href=\"#\">Sci Fi\u00a0<\/a> \u00a0 <a href=\"#\">Horror<\/a>\u00a0<\/strong><\/p><p class=\"p1\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33f5ac8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33f5ac8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0207643\" data-id=\"0207643\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10087fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10087fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f54fd3\" data-id=\"1f54fd3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5933818 elementor-widget elementor-widget-heading\" data-id=\"5933818\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Kids<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9d6595d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9d6595d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d25cd91\" data-id=\"d25cd91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b2ecd3 elementor-widget elementor-widget-image\" data-id=\"4b2ecd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3dce303\" data-id=\"3dce303\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b09243 elementor-widget elementor-widget-image\" data-id=\"6b09243\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-890ca9b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"890ca9b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ae034d1\" data-id=\"ae034d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68d3009 elementor-widget elementor-widget-heading\" data-id=\"68d3009\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Action \/ Adventure<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e5df799 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5df799\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0d49547\" data-id=\"0d49547\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-759b029 elementor-widget elementor-widget-image\" data-id=\"759b029\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6b6b7fc\" data-id=\"6b6b7fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b25b73 elementor-widget elementor-widget-image\" data-id=\"9b25b73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d918dd6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d918dd6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-943b4bc\" data-id=\"943b4bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7ecf33 elementor-widget elementor-widget-heading\" data-id=\"d7ecf33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Romance<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e432f90 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e432f90\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-613d0b5\" data-id=\"613d0b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6998498 elementor-widget elementor-widget-image\" data-id=\"6998498\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c740eba\" data-id=\"c740eba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4be35bc elementor-widget elementor-widget-image\" data-id=\"4be35bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ontheflipsidecomics.com\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef5e463 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef5e463\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-517caf0\" data-id=\"517caf0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02e348a elementor-widget elementor-widget-text-editor\" data-id=\"02e348a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"#\"><strong>NEXT<\/strong><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9c7785e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9c7785e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-845470c\" data-id=\"845470c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3266607 elementor-widget elementor-widget-text-editor\" data-id=\"3266607\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><a href=\"#\">PREVIOUS<\/a> | <a href=\"#\">NEXT<\/a><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Comics Index Pick A Category &#038; START READIN&#8217; Kids\u00a0 \u00a0 Action \/ Adventure\u00a0 \u00a0 \u00a0Romance\u00a0 \u00a0 Humor\u00a0 \u00a0 Flipside Originals\u00a0 \u00a0 Fantasy\u00a0 \u00a0 Sci Fi\u00a0 \u00a0 Horror\u00a0 \u00a0 Kids\u00a0 \u00a0 Action \/ Adventure\u00a0 \u00a0 \u00a0Romance\u00a0 \u00a0 Humor\u00a0 \u00a0 Flipside Originals\u00a0 \u00a0 Fantasy\u00a0 \u00a0 Sci Fi\u00a0 \u00a0 Horror\u00a0 \u00a0 Adult \u00a0 Kids Action \/ Adventure Romance [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-6450","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comics Index - Where Past and Present Collide to Make the Future<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ontheflipsidecomics.com\/nl\/comics-index\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"ar\" \/>\n<meta property=\"og:locale:alternate\" content=\"de_DE\" \/>\n<meta property=\"og:locale:alternate\" content=\"es_MX\" \/>\n<meta property=\"og:locale:alternate\" content=\"fr_FR\" \/>\n<meta property=\"og:locale:alternate\" content=\"it_IT\" \/>\n<meta property=\"og:locale:alternate\" content=\"ja\" \/>\n<meta property=\"og:locale:alternate\" content=\"ko_KR\" \/>\n<meta property=\"og:locale:alternate\" content=\"pt_BR\" \/>\n<meta property=\"og:locale:alternate\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comics Index - Where Past and Present Collide to Make the Future\" \/>\n<meta property=\"og:description\" content=\"Comics Index Pick A Category &amp; START READIN&#8217; Kids\u00a0 \u00a0 Action \/ Adventure\u00a0 \u00a0 \u00a0Romance\u00a0 \u00a0 Humor\u00a0 \u00a0 Flipside Originals\u00a0 \u00a0 Fantasy\u00a0 \u00a0 Sci Fi\u00a0 \u00a0 Horror\u00a0 \u00a0 Kids\u00a0 \u00a0 Action \/ Adventure\u00a0 \u00a0 \u00a0Romance\u00a0 \u00a0 Humor\u00a0 \u00a0 Flipside Originals\u00a0 \u00a0 Fantasy\u00a0 \u00a0 Sci Fi\u00a0 \u00a0 Horror\u00a0 \u00a0 Adult \u00a0 Kids Action \/ Adventure Romance [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ontheflipsidecomics.com\/nl\/comics-index\/\" \/>\n<meta property=\"og:site_name\" content=\"Flipside Comics\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089482013557\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-21T11:58:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ontheflipsidecomics.com\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@FlipsideComix\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/en\\\/comics-index\\\/\",\"url\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/en\\\/comics-index\\\/\",\"name\":\"Comics Index - Where Past and Present Collide to Make the Future\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/en\\\/comics-index\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/en\\\/comics-index\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/wp-content\\\/plugins\\\/elementor\\\/assets\\\/images\\\/placeholder.png\",\"datePublished\":\"2024-02-17T19:21:01+00:00\",\"dateModified\":\"2024-02-21T11:58:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/en\\\/comics-index\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ontheflipsidecomics.com\\\/en\\\/comics-index\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/en\\\/comics-index\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/wp-content\\\/plugins\\\/elementor\\\/assets\\\/images\\\/placeholder.png\",\"contentUrl\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/wp-content\\\/plugins\\\/elementor\\\/assets\\\/images\\\/placeholder.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/en\\\/comics-index\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comics Index\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/\",\"name\":\"OntheFlipsideComics\",\"description\":\"Where Past and Present Collide to Make the Future\",\"publisher\":{\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/#organization\",\"name\":\"Flipside Comics\",\"alternateName\":\"Flipside Comix\",\"url\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LBC_logo-2.png\",\"contentUrl\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/LBC_logo-2.png\",\"width\":295,\"height\":199,\"caption\":\"Flipside Comics\"},\"image\":{\"@id\":\"https:\\\/\\\/ontheflipsidecomics.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089482013557\",\"https:\\\/\\\/x.com\\\/FlipsideComix\",\"https:\\\/\\\/bsky.app\\\/profile\\\/flipsidecomics.bsky.social\",\"https:\\\/\\\/www.instagram.com\\\/flipsidecomix\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comics Index - Where Past and Present Collide to Make the Future","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ontheflipsidecomics.com\/nl\/comics-index\/","og_locale":"nl_NL","og_type":"article","og_title":"Comics Index - Where Past and Present Collide to Make the Future","og_description":"Comics Index Pick A Category &#038; START READIN&#8217; Kids\u00a0 \u00a0 Action \/ Adventure\u00a0 \u00a0 \u00a0Romance\u00a0 \u00a0 Humor\u00a0 \u00a0 Flipside Originals\u00a0 \u00a0 Fantasy\u00a0 \u00a0 Sci Fi\u00a0 \u00a0 Horror\u00a0 \u00a0 Kids\u00a0 \u00a0 Action \/ Adventure\u00a0 \u00a0 \u00a0Romance\u00a0 \u00a0 Humor\u00a0 \u00a0 Flipside Originals\u00a0 \u00a0 Fantasy\u00a0 \u00a0 Sci Fi\u00a0 \u00a0 Horror\u00a0 \u00a0 Adult \u00a0 Kids Action \/ Adventure Romance [&hellip;]","og_url":"https:\/\/ontheflipsidecomics.com\/nl\/comics-index\/","og_site_name":"Flipside Comics","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100089482013557","article_modified_time":"2024-02-21T11:58:41+00:00","og_image":[{"url":"https:\/\/ontheflipsidecomics.com\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@FlipsideComix","twitter_misc":{"Geschatte leestijd":"2 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ontheflipsidecomics.com\/en\/comics-index\/","url":"https:\/\/ontheflipsidecomics.com\/en\/comics-index\/","name":"Comics Index - Where Past and Present Collide to Make the Future","isPartOf":{"@id":"https:\/\/ontheflipsidecomics.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ontheflipsidecomics.com\/en\/comics-index\/#primaryimage"},"image":{"@id":"https:\/\/ontheflipsidecomics.com\/en\/comics-index\/#primaryimage"},"thumbnailUrl":"https:\/\/ontheflipsidecomics.com\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png","datePublished":"2024-02-17T19:21:01+00:00","dateModified":"2024-02-21T11:58:41+00:00","breadcrumb":{"@id":"https:\/\/ontheflipsidecomics.com\/en\/comics-index\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ontheflipsidecomics.com\/en\/comics-index\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/ontheflipsidecomics.com\/en\/comics-index\/#primaryimage","url":"https:\/\/ontheflipsidecomics.com\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png","contentUrl":"https:\/\/ontheflipsidecomics.com\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png"},{"@type":"BreadcrumbList","@id":"https:\/\/ontheflipsidecomics.com\/en\/comics-index\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ontheflipsidecomics.com\/it\/"},{"@type":"ListItem","position":2,"name":"Comics Index"}]},{"@type":"WebSite","@id":"https:\/\/ontheflipsidecomics.com\/it\/#website","url":"https:\/\/ontheflipsidecomics.com\/it\/","name":"OntheFlipsideComics","description":"Where Past and Present Collide to Make the Future","publisher":{"@id":"https:\/\/ontheflipsidecomics.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ontheflipsidecomics.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/ontheflipsidecomics.com\/it\/#organization","name":"Flipside Comics","alternateName":"Flipside Comix","url":"https:\/\/ontheflipsidecomics.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/ontheflipsidecomics.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2022\/08\/LBC_logo-2.png","contentUrl":"https:\/\/ontheflipsidecomics.com\/wp-content\/uploads\/2022\/08\/LBC_logo-2.png","width":295,"height":199,"caption":"Flipside Comics"},"image":{"@id":"https:\/\/ontheflipsidecomics.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100089482013557","https:\/\/x.com\/FlipsideComix","https:\/\/bsky.app\/profile\/flipsidecomics.bsky.social","https:\/\/www.instagram.com\/flipsidecomix\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ontheflipsidecomics.com\/nl\/wp-json\/wp\/v2\/pages\/6450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ontheflipsidecomics.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ontheflipsidecomics.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ontheflipsidecomics.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ontheflipsidecomics.com\/nl\/wp-json\/wp\/v2\/comments?post=6450"}],"version-history":[{"count":76,"href":"https:\/\/ontheflipsidecomics.com\/nl\/wp-json\/wp\/v2\/pages\/6450\/revisions"}],"predecessor-version":[{"id":6691,"href":"https:\/\/ontheflipsidecomics.com\/nl\/wp-json\/wp\/v2\/pages\/6450\/revisions\/6691"}],"wp:attachment":[{"href":"https:\/\/ontheflipsidecomics.com\/nl\/wp-json\/wp\/v2\/media?parent=6450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}